{"id":806,"count":3,"description":"","link":"https:\/\/melanditravel.com\/en\/tag\/night-market-en\/","name":"Night Market","slug":"night-market-en","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/tags\/806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/posts?tags=806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}