{"id":662,"count":2,"description":"","link":"https:\/\/melanditravel.com\/en\/tag\/vakil-bath\/","name":"Vakil Bath","slug":"vakil-bath","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/tags\/662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/posts?tags=662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}