{"id":498,"count":3,"description":"","link":"https:\/\/melanditravel.com\/en\/tag\/islamabad-en\/","name":"Islamabad","slug":"islamabad-en","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/tags\/498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/melanditravel.com\/en\/wp-json\/wp\/v2\/posts?tags=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}